{"id":25831,"date":"2017-10-24T09:08:02","date_gmt":"2017-10-24T09:08:02","guid":{"rendered":"http:\/\/gracadivina.com\/?p=25831"},"modified":"2017-10-31T15:15:17","modified_gmt":"2017-10-31T15:15:17","slug":"a-escolha-lei-e-obras-ou-fe-e-graca","status":"publish","type":"post","link":"https:\/\/gracadivina.com\/index.php\/2017\/10\/24\/a-escolha-lei-e-obras-ou-fe-e-graca\/","title":{"rendered":"A escolha: Lei e obras, ou f\u00e9 e gra\u00e7a?"},"content":{"rendered":"<div class=\"row \"><div class=\"wpv-grid grid-1-1  wpv-first-level first unextended\" style=\"padding-top:0px;padding-bottom:0px\" id=\"wpv-column-314a1e4ebe93089c783802e5503a57f5\" ><h2><a href=\"http:\/\/gracadivina.com\/wp-content\/uploads\/2017\/10\/escolha.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-25834 alignleft\" src=\"http:\/\/gracadivina.com\/wp-content\/uploads\/2017\/10\/escolha-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/gracadivina.com\/wp-content\/uploads\/2017\/10\/escolha-200x300.jpg 200w, https:\/\/gracadivina.com\/wp-content\/uploads\/2017\/10\/escolha-360x540.jpg 360w, https:\/\/gracadivina.com\/wp-content\/uploads\/2017\/10\/escolha-262x393.jpg 262w, https:\/\/gracadivina.com\/wp-content\/uploads\/2017\/10\/escolha.jpg 400w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>Porque pela gra\u00e7a sois salvos, por meio da f\u00e9; e isto n\u00e3o vem de v\u00f3s, \u00e9 dom de Deus<\/h2>\n<h4>-Ef 2:8<\/h4>\n<p>\u201c\u00c9 melhor cair em gra\u00e7a, que ser engra\u00e7ado\u201d \u2013 diz a sabedoria popular. Ou seja, nos deixarmos simplesmente cair na gra\u00e7a (ser sinceros, nos mostrar tal qual somos), ao inv\u00e9s de nos esfor\u00e7ar por a alcan\u00e7ar (pretender impressionar a Deus ou aos homens). Sendo a gra\u00e7a oferecida, insulta a Deus quem quiser pagar o seu custo. Se pudesse ser paga com obra nossa, a de Jesus seria desnecess\u00e1ria. \u00c9 isto que ensinam aqueles que pregam a lei e as obras como modo de obter a salva\u00e7\u00e3o. Quem acreditar que precisar\u00e1 cumprir a lei e fazer as boas obras para alcan\u00e7ar gra\u00e7a, estar\u00e1 dizendo a Deus que tem algo melhor que o sacrif\u00edcio de Seu filho na cruz; que a Sua vinda e todo o seu sofrimento, foi um ato mal calculado do Criador. Estar\u00e1 colocando a confian\u00e7a em si mesmo, n\u00e3o no Salvador.<\/p>\n<p>Mas ent\u00e3o a lei e as obras n\u00e3o contam?<\/p>\n<p>Est\u00e1 escrito que n\u00e3o se pode servir a dois senhores: h\u00e1 que amar um e aborrecer o outro, desprezar um e amar o outro. Ou seja, servir a Deus ou a Mamon (Mt6:24). Ora n\u00e3o faria sentido Deus dizer-nos para odiar e desprezar o dinheiro, e em seguida vir falar de d\u00edzimos e ofertas; quereria Deus para Si, o que nos diz para desprezarmos&#8230;?<\/p>\n<p>&#8211; De certeza que n\u00e3o; a quest\u00e3o est\u00e1, a qual dos dois damos o primeiro lugar. Ou seja, dando d\u00edzimo e oferta, estamos amando e servindo a Deus; se n\u00e3o, lhe estaremos desobedecendo, colocando o dinheiro \u00e0 frente da vontade de Deus. N\u00e3o temos que abominar o dinheiro, mas colocar Deus em primeiro lugar. Portanto a quest\u00e3o n\u00e3o est\u00e1 realmente em desprezar o dinheiro, a lei, ou as obras; mas em crer no que o Senhor diz (\u201cn\u00e3o chames impuro ao que Deus purificou\u201d &#8211; At11:9).<\/p>\n<p>H\u00e1 que perceber: A salva\u00e7\u00e3o se alcan\u00e7a por gra\u00e7a, atrav\u00e9s da f\u00e9 em Cristo; mas a recompensa que cada um receber\u00e1 para a eternidade, \u00e9 acumulada agora no c\u00e9u, pelas boas obras realizadas nesta vida, obedecendo a Cristo.<\/p>\n<p>O s\u00e1bio demonstra a sua sabedoria pelo que diz e faz, no modo como vive. As obras s\u00e3o a manifesta\u00e7\u00e3o vis\u00edvel do que realmente cremos e somos!<br \/>\nA f\u00e9 vem do esp\u00edrito, as obras do corpo. Tal como a vida que est\u00e1 no sangue nutre e faz mover o corpo, se a f\u00e9 estiver presente no esp\u00edrito, se manifestar\u00e1 em boas obras.<br \/>\n\u00c9 a conjuga\u00e7\u00e3o do esp\u00edrito com o corpo, o que permite a nossa presente exist\u00eancia; a f\u00e9 e as obras s\u00e3o como corpo e esp\u00edrito: separados, fica um cad\u00e1ver&#8230; A f\u00e9 somada a obras, \u00e9 igual a vida; somada a zero, \u00e9 igual a morte (F\u00e9 + obras = Um corpo vivo; F\u00e9 + zero = Um cad\u00e1ver).<br \/>\nS\u00e3o as nossas obras de f\u00e9, que provam sermos justos. O aperfei\u00e7oamento do crist\u00e3o estar\u00e1 completo, quando o corpo fizer o que o esp\u00edrito cr\u00ea. Se algu\u00e9m diz que n\u00e3o tem obras, mas tem f\u00e9, que prove; pois a f\u00e9 sempre foi comprovada com obras \u2013 foi por elas que os antigos deixaram testemunho.<\/p>\n<p>As obras s\u00e3o o corpo da f\u00e9. S\u00e3o a materializa\u00e7\u00e3o, a corporiza\u00e7\u00e3o, a substancia, a forma vis\u00edvel da f\u00e9; a prova de que existe, est\u00e1 viva!<\/p>\n<p>F\u00e9, \u00e9 viver como Cristo viveu: pela Palavra de Deus!<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A salva\u00e7\u00e3o se alcan\u00e7a por gra\u00e7a, atrav\u00e9s da f\u00e9 em Cristo; mas a recompensa que cada um receber\u00e1 para a eternidade, \u00e9 acumulada agora no c\u00e9u, pelas boas obras realizadas nesta vida, obedecendo a Cristo.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"categories":[119],"tags":[128,163,164,145,124,162,123],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A escolha: Lei e obras, ou f\u00e9 e gra\u00e7a? - Gra\u00e7a Divina<\/title>\n<meta name=\"description\" content=\"Porque pela gra\u00e7a sois salvos, por meio da f\u00e9\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gracadivina.com\/index.php\/2017\/10\/24\/a-escolha-lei-e-obras-ou-fe-e-graca\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A escolha: Lei e obras, ou f\u00e9 e gra\u00e7a? - Gra\u00e7a Divina\" \/>\n<meta property=\"og:description\" content=\"Porque pela gra\u00e7a sois salvos, por meio da f\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gracadivina.com\/index.php\/2017\/10\/24\/a-escolha-lei-e-obras-ou-fe-e-graca\/\" \/>\n<meta property=\"og:site_name\" content=\"Gra\u00e7a Divina\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-24T09:08:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-31T15:15:17+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/gracadivina.com\/wp-content\/uploads\/2017\/10\/escolha-200x300.jpg\" \/>\n<meta name=\"author\" content=\"Gra\u00e7a Divina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gra\u00e7a Divina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gracadivina.com\/index.php\/2017\/10\/24\/a-escolha-lei-e-obras-ou-fe-e-graca\/\",\"url\":\"https:\/\/gracadivina.com\/index.php\/2017\/10\/24\/a-escolha-lei-e-obras-ou-fe-e-graca\/\",\"name\":\"A escolha: Lei e obras, ou f\u00e9 e gra\u00e7a? - Gra\u00e7a Divina\",\"isPartOf\":{\"@id\":\"https:\/\/gracadivina.com\/#website\"},\"datePublished\":\"2017-10-24T09:08:02+00:00\",\"dateModified\":\"2017-10-31T15:15:17+00:00\",\"author\":{\"@id\":\"https:\/\/gracadivina.com\/#\/schema\/person\/94e0f9ee09e1b11376eb7e9930abc2f5\"},\"description\":\"Porque pela gra\u00e7a sois salvos, por meio da f\u00e9\",\"breadcrumb\":{\"@id\":\"https:\/\/gracadivina.com\/index.php\/2017\/10\/24\/a-escolha-lei-e-obras-ou-fe-e-graca\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gracadivina.com\/index.php\/2017\/10\/24\/a-escolha-lei-e-obras-ou-fe-e-graca\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gracadivina.com\/index.php\/2017\/10\/24\/a-escolha-lei-e-obras-ou-fe-e-graca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/gracadivina.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A escolha: Lei e obras, ou f\u00e9 e gra\u00e7a?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gracadivina.com\/#website\",\"url\":\"https:\/\/gracadivina.com\/\",\"name\":\"Gra\u00e7a Divina\",\"description\":\"Igreja evang\u00e9lica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gracadivina.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/gracadivina.com\/#\/schema\/person\/94e0f9ee09e1b11376eb7e9930abc2f5\",\"name\":\"Gra\u00e7a Divina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/gracadivina.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f7160a870435ef7d747e68e088291e04?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f7160a870435ef7d747e68e088291e04?s=96&d=mm&r=g\",\"caption\":\"Gra\u00e7a Divina\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A escolha: Lei e obras, ou f\u00e9 e gra\u00e7a? - Gra\u00e7a Divina","description":"Porque pela gra\u00e7a sois salvos, por meio da f\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gracadivina.com\/index.php\/2017\/10\/24\/a-escolha-lei-e-obras-ou-fe-e-graca\/","og_locale":"pt_PT","og_type":"article","og_title":"A escolha: Lei e obras, ou f\u00e9 e gra\u00e7a? - Gra\u00e7a Divina","og_description":"Porque pela gra\u00e7a sois salvos, por meio da f\u00e9","og_url":"https:\/\/gracadivina.com\/index.php\/2017\/10\/24\/a-escolha-lei-e-obras-ou-fe-e-graca\/","og_site_name":"Gra\u00e7a Divina","article_published_time":"2017-10-24T09:08:02+00:00","article_modified_time":"2017-10-31T15:15:17+00:00","og_image":[{"url":"http:\/\/gracadivina.com\/wp-content\/uploads\/2017\/10\/escolha-200x300.jpg"}],"author":"Gra\u00e7a Divina","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gra\u00e7a Divina","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gracadivina.com\/index.php\/2017\/10\/24\/a-escolha-lei-e-obras-ou-fe-e-graca\/","url":"https:\/\/gracadivina.com\/index.php\/2017\/10\/24\/a-escolha-lei-e-obras-ou-fe-e-graca\/","name":"A escolha: Lei e obras, ou f\u00e9 e gra\u00e7a? - Gra\u00e7a Divina","isPartOf":{"@id":"https:\/\/gracadivina.com\/#website"},"datePublished":"2017-10-24T09:08:02+00:00","dateModified":"2017-10-31T15:15:17+00:00","author":{"@id":"https:\/\/gracadivina.com\/#\/schema\/person\/94e0f9ee09e1b11376eb7e9930abc2f5"},"description":"Porque pela gra\u00e7a sois salvos, por meio da f\u00e9","breadcrumb":{"@id":"https:\/\/gracadivina.com\/index.php\/2017\/10\/24\/a-escolha-lei-e-obras-ou-fe-e-graca\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gracadivina.com\/index.php\/2017\/10\/24\/a-escolha-lei-e-obras-ou-fe-e-graca\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gracadivina.com\/index.php\/2017\/10\/24\/a-escolha-lei-e-obras-ou-fe-e-graca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gracadivina.com\/"},{"@type":"ListItem","position":2,"name":"A escolha: Lei e obras, ou f\u00e9 e gra\u00e7a?"}]},{"@type":"WebSite","@id":"https:\/\/gracadivina.com\/#website","url":"https:\/\/gracadivina.com\/","name":"Gra\u00e7a Divina","description":"Igreja evang\u00e9lica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gracadivina.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/gracadivina.com\/#\/schema\/person\/94e0f9ee09e1b11376eb7e9930abc2f5","name":"Gra\u00e7a Divina","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/gracadivina.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f7160a870435ef7d747e68e088291e04?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f7160a870435ef7d747e68e088291e04?s=96&d=mm&r=g","caption":"Gra\u00e7a Divina"}}]}},"_links":{"self":[{"href":"https:\/\/gracadivina.com\/index.php\/wp-json\/wp\/v2\/posts\/25831"}],"collection":[{"href":"https:\/\/gracadivina.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gracadivina.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gracadivina.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gracadivina.com\/index.php\/wp-json\/wp\/v2\/comments?post=25831"}],"version-history":[{"count":5,"href":"https:\/\/gracadivina.com\/index.php\/wp-json\/wp\/v2\/posts\/25831\/revisions"}],"predecessor-version":[{"id":25837,"href":"https:\/\/gracadivina.com\/index.php\/wp-json\/wp\/v2\/posts\/25831\/revisions\/25837"}],"wp:attachment":[{"href":"https:\/\/gracadivina.com\/index.php\/wp-json\/wp\/v2\/media?parent=25831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gracadivina.com\/index.php\/wp-json\/wp\/v2\/categories?post=25831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gracadivina.com\/index.php\/wp-json\/wp\/v2\/tags?post=25831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}